{"id":861,"date":"2013-11-05T00:32:02","date_gmt":"2013-11-05T02:32:02","guid":{"rendered":"http:\/\/www.encontrapetropolis.com.br\/noticias\/?p=861"},"modified":"2013-11-04T23:34:08","modified_gmt":"2013-11-05T01:34:08","slug":"plano-diretor-de-petropolis-recebera-emendas-a-partir-desta-sexta","status":"publish","type":"post","link":"https:\/\/www.encontrapetropolis.com.br\/noticias\/plano-diretor-de-petropolis-recebera-emendas-a-partir-desta-sexta\/","title":{"rendered":"Plano Diretor de Petr\u00f3polis receber\u00e1 emendas a partir desta sexta"},"content":{"rendered":"<p>A Comiss\u00e3o Especial de Revis\u00e3o e Estudos do Plano Diretor da C\u00e2mara Municipal de Petr\u00f3polis, Regi\u00e3o Serrana do Rio, realizar\u00e1 audi\u00eancia p\u00fablica nesta quinta-feira (7), \u00e0s 19h30, para instruir a popula\u00e7\u00e3o sobre o prazo para a apresenta\u00e7\u00e3o de emendas. A reuni\u00e3o acontecer\u00e1 no audit\u00f3rio da Faculdade Arthur S\u00e1 Earp Neto (Fase), na Avenida Bar\u00e3o do Rio Branco, n\u00ba 1003, no Centro.<\/p>\n<p>As emendas poder\u00e3o ser apresentadas a partir desta sexta-feira (8) at\u00e9 o dia 22 de novembro. O Plano Diretor de Petr\u00f3polis (PDP) tem como principal finalidade estabelecer diretrizes para orientar o processo de planejamento participativo. Dessa forma, as sugest\u00f5es e opini\u00f5es da popula\u00e7\u00e3o s\u00e3o fundamentais e dever\u00e3o ser encaminhadas \u00e0 C\u00e2mara por meio do site oficial ou diretamente no local, na Pra\u00e7a Visconde de Mau\u00e1, n\u00ba 89, no Centro. As sugest\u00f5es devem ser protocoladas na Secretaria Legislativa.<\/p>\n<p>O presidente da comiss\u00e3o, o vereador Thiago Damaceno, afirma que \u201ceste \u00e9 o momento no qual o cidad\u00e3o pode participar ativamente da constru\u00e7\u00e3o do plano, podendo alterar o texto final da lei\u201d. Poder\u00e3o ser feitas emendas aditivas (acr\u00e9scimo \u00e0 proposi\u00e7\u00e3o inicial), supressivas (pedido de retirada de parte do texto ou da lei inteira) e modificativas (altera\u00e7\u00e3o em parte o projeto de lei). \u00c9 poss\u00edvel fazer ainda emendas de reda\u00e7\u00e3o (corre\u00e7\u00f5es de reda\u00e7\u00e3o ou linguagem) e subemendas (inclus\u00e3o de especifica\u00e7\u00f5es).<\/p>\n<p>As emendas ser\u00e3o votadas pelos vereadores em plen\u00e1rio. Segundo o artigo 2\u00ba da Lei 6321\/05, que institui o PDP, quatro setores de pol\u00edticas p\u00fablicas s\u00e3o considerados como b\u00e1sicos: desenvolvimento humano, econ\u00f4mico, institucional e de infraestrutura. Antes do per\u00edodo de apresenta\u00e7\u00e3o de emendas, dez audi\u00eancias p\u00fablicas foram realizadas em pontos diferentes da cidade com o objetivo de mostrar as fun\u00e7\u00f5es e a import\u00e2ncia do Plano Diretor para o desenvolvimento da cidade nos pr\u00f3ximos dez anos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o Especial de Revis\u00e3o e Estudos do Plano Diretor da C\u00e2mara Municipal de Petr\u00f3polis, Regi\u00e3o Serrana do Rio, realizar\u00e1 audi\u00eancia p\u00fablica nesta quinta-feira (7), \u00e0s 19h30, para instruir a popula\u00e7\u00e3o sobre o prazo para a apresenta\u00e7\u00e3o de emendas. A reuni\u00e3o acontecer\u00e1 no audit\u00f3rio da Faculdade Arthur S\u00e1 Earp Neto (Fase), na Avenida Bar\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.encontrapetropolis.com.br\/noticias\/wp-json\/wp\/v2\/posts\/861"}],"collection":[{"href":"https:\/\/www.encontrapetropolis.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapetropolis.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapetropolis.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapetropolis.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=861"}],"version-history":[{"count":1,"href":"https:\/\/www.encontrapetropolis.com.br\/noticias\/wp-json\/wp\/v2\/posts\/861\/revisions"}],"predecessor-version":[{"id":862,"href":"https:\/\/www.encontrapetropolis.com.br\/noticias\/wp-json\/wp\/v2\/posts\/861\/revisions\/862"}],"wp:attachment":[{"href":"https:\/\/www.encontrapetropolis.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapetropolis.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapetropolis.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}